{"id":32814,"date":"2019-03-29T16:30:31","date_gmt":"2019-03-29T15:30:31","guid":{"rendered":"https:\/\/www.rafraichisseur-air.fr\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/"},"modified":"2024-07-08T15:33:53","modified_gmt":"2024-07-08T14:33:53","slug":"deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec","status":"publish","type":"page","link":"https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/","title":{"rendered":"Deodoranti per ambienti a motore EC: il nostro modello FoxAir 36 EC"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"32814\" class=\"elementor elementor-32814 elementor-13163\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bc9dfa7 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qodef_elementor_container_no\" data-id=\"3bc9dfa7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;opacity-tilt&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 2600 131.1\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L2600 0 2600 69.1 0 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.5\" d=\"M0 0L2600 0 2600 69.1 0 69.1z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.25\" d=\"M2600 0L0 0 0 130.1 2600 69.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10cdbb04\" data-id=\"10cdbb04\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-730ad81c qodef_elementor_container_inner elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"730ad81c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3b139c1\" data-id=\"3b139c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fccc716 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fccc716\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Deodoranti per ambienti a motore EC: il nostro modello FoxAir 36 EC\n\n\n<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-290103e elementor-widget elementor-widget-spacer\" data-id=\"290103e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4dd03431 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qodef_elementor_container_no\" data-id=\"4dd03431\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-666eb154\" data-id=\"666eb154\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-35b5c922 qodef_elementor_container_inner elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"35b5c922\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-469c36f\" data-id=\"469c36f\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cb19d3c elementor-widget elementor-widget-text-editor\" data-id=\"6cb19d3c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Sei un cliente fedele di FoxAir e conosci gi\u00e0 la nostra gamma, ma hai mai sentito parlare del nostro <strong>deodorante a motore EC<\/strong>? Lascia che ti presentiamo!<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e2857ab elementor-widget elementor-widget-spacer\" data-id=\"6e2857ab\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58e91c10 elementor-widget elementor-widget-text-editor\" data-id=\"58e91c10\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>FoxAir 36 EC \u00e8 un deodorante per ambienti con una tecnologia innovativa. La sua ventola \u00e8 alimentata da un motore a commutazione elettronica, che ne migliora notevolmente l&#8217;efficienza energetica.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-517a9319 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qodef_elementor_container_no\" data-id=\"517a9319\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-615cbc04\" data-id=\"615cbc04\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6dbc09c elementor-section-content-top qodef_elementor_container_inner elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"6dbc09c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-47aa3ecc\" data-id=\"47aa3ecc\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78aca578 elementor-widget elementor-widget-image\" data-id=\"78aca578\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.rafraichisseur-air.fr\/wp-content\/uploads\/elementor\/thumbs\/rafraichisseur-dair-2-p4om43po047vwbw02w1ajqvxri9o0n2rckuny1ed9c.jpg\" title=\"rafraichisseur-dair-2\" alt=\"rafraichisseur-dair-2\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4e73afc8\" data-id=\"4e73afc8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12e37d9e elementor-widget elementor-widget-text-editor\" data-id=\"12e37d9e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>Un deodorante per ambienti con un motore rivoluzionario\n<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5efde15 elementor-widget elementor-widget-spacer\" data-id=\"5efde15\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-202a73f5 elementor-widget elementor-widget-text-editor\" data-id=\"202a73f5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Cosa significa esattamente? Semplicemente, riducendo il consumo energetico e aumentando la durata del motore! Il che, diciamolo, \u00e8 ottimo per un uso prolungato!<\/p>\n<p>Altri vantaggi del <strong>radiatore del motore EC<\/strong>: un motore molto pi\u00f9 silenzioso, una maggiore efficienza e una potenza nettamente superiore. Tutti questi vantaggi la rendono particolarmente adatta a climatizzare grandi superfici in ambito professionale.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7132cf93 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qodef_elementor_container_no\" data-id=\"7132cf93\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5f35f95\" data-id=\"5f35f95\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-353b1e4 elementor-section-content-top qodef_elementor_container_inner elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"353b1e4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-30ac5e8e\" data-id=\"30ac5e8e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9a96a5 elementor-widget elementor-widget-text-editor\" data-id=\"f9a96a5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>Un&#8217;alternativa ideale alla climatizzazione integrata\n<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22fd554 elementor-widget elementor-widget-spacer\" data-id=\"22fd554\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d66f1f1 elementor-widget elementor-widget-text-editor\" data-id=\"1d66f1f1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Oltre a tutte le qualit\u00e0 che abbiamo appena descritto, la cosa migliore del <strong>raffreddatore d&#8217;aria a ventola con motore EC<\/strong> \u00e8 che \u00e8 mobile.<\/p>\n<p>Con il nostro modello FoxAir 36 EC non c&#8217;\u00e8 bisogno di installare un costoso impianto di condizionamento nei tuoi locali: puoi posizionarlo dove vuoi e spostarlo a tuo piacimento. Basta collegarlo a un alimentatore e si parte! Come gli altri modelli, pu\u00f2 essere collegato a un circuito idrico per evitare di dover riempire troppo spesso il serbatoio.<\/p>\n<p>Infine, la potenza del suo motore (550W) permette di raffreddare fino a 260 m\u00b2. Se vuoi utilizzarlo in un grande open space, \u00e8 la soluzione ideale per permettere ai tuoi dipendenti di lavorare in un ambiente fresco a costi ridotti!<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7e9f34b7\" data-id=\"7e9f34b7\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9fe1b5 elementor-widget elementor-widget-video\" data-id=\"c9fe1b5\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=60MKGlPbnzw&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section style=\"background-image: url(https:\/\/www.rafraichisseur-air.fr\/wp-content\/uploads\/2021\/02\/background-foxair-3.jpg); min-height: 0px\" class=\"qodef-parallax-section-holder qodef-parallax-section-holder-touch-disabled elementor-section elementor-top-section elementor-element elementor-element-57217d16 elementor-section-full_width parallax_section_holder ctabackground elementor-section-height-default elementor-section-height-default qodef_elementor_container_no\" data-qodef-parallax-speed=\"0\" data-id=\"57217d16\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;tilt&quot;,&quot;qode_parallax_image&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.rafraichisseur-air.fr\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/background-foxair-3.jpg&quot;,&quot;id&quot;:17062,&quot;size&quot;:&quot;&quot;}}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7be9464a\" data-id=\"7be9464a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6a7db128 elementor-section-content-top qodef_elementor_container_inner elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"6a7db128\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6a637443\" data-id=\"6a637443\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4f1d6134\" data-id=\"4f1d6134\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27a1d42a elementor-widget elementor-widget-text-editor\" data-id=\"27a1d42a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>FOXAIR \u00e8 un raffreddatore d&#8217;aria semplice ed efficace<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53a974ec elementor-widget elementor-widget-text-editor\" data-id=\"53a974ec\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Offre una serie di vantaggi: non richiede installazione, \u00e8 mobile, ecologico ed economico&#8230;<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb98ae0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"bb98ae0\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-pop\" href=\"tel:+33478844000\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\"><i class=\"menu_icon icon-phone fa\"><\/i>  +33 4 78 84 40 00<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f915bcc elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3f915bcc\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-pop\" href=\"https:\/\/www.rafraichisseur-air.fr\/contact-rafraichisseur-air\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi un preventivo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d0fcbfa elementor-widget elementor-widget-spacer\" data-id=\"3d0fcbfa\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Deodoranti per ambienti a motore EC: il nostro modello FoxAir 36 EC Sei un cliente fedele di FoxAir e conosci gi\u00e0&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Deodoranti a motore EC: scopri FoxAir 36 EC<\/title>\n<meta name=\"description\" content=\"Scopri il nostro raffreddatore ad aria con motore EC. Con FoxAir 36 EC puoi raffreddare fino a 260 m\u00b2 e ridurre il consumo energetico grazie all&#039;innovativo motore a commutazione elettronica. Pi\u00f9 potente, pi\u00f9 silenzioso, ha tutte le carte in regola!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deodoranti a motore EC: scopri FoxAir 36 EC\" \/>\n<meta property=\"og:description\" content=\"Scopri il nostro raffreddatore ad aria con motore EC. Con FoxAir 36 EC puoi raffreddare fino a 260 m\u00b2 e ridurre il consumo energetico grazie all&#039;innovativo motore a commutazione elettronica. Pi\u00f9 potente, pi\u00f9 silenzioso, ha tutte le carte in regola!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/\" \/>\n<meta property=\"og:site_name\" content=\"Foxair\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/foxair.france\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-08T14:33:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rafraichisseur-air.fr\/wp-content\/uploads\/elementor\/thumbs\/rafraichisseur-dair-2-p4om43po047vwbw02w1ajqvxri9o0n2rckuny1ed9c.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/\",\"url\":\"https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/\",\"name\":\"Deodoranti a motore EC: scopri FoxAir 36 EC\",\"isPartOf\":{\"@id\":\"https:\/\/www.rafraichisseur-air.fr\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.rafraichisseur-air.fr\/wp-content\/uploads\/elementor\/thumbs\/rafraichisseur-dair-2-p4om43po047vwbw02w1ajqvxri9o0n2rckuny1ed9c.jpg\",\"datePublished\":\"2019-03-29T15:30:31+00:00\",\"dateModified\":\"2024-07-08T14:33:53+00:00\",\"description\":\"Scopri il nostro raffreddatore ad aria con motore EC. Con FoxAir 36 EC puoi raffreddare fino a 260 m\u00b2 e ridurre il consumo energetico grazie all'innovativo motore a commutazione elettronica. Pi\u00f9 potente, pi\u00f9 silenzioso, ha tutte le carte in regola!\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/#primaryimage\",\"url\":\"https:\/\/www.rafraichisseur-air.fr\/wp-content\/uploads\/elementor\/thumbs\/rafraichisseur-dair-2-p4om43po047vwbw02w1ajqvxri9o0n2rckuny1ed9c.jpg\",\"contentUrl\":\"https:\/\/www.rafraichisseur-air.fr\/wp-content\/uploads\/elementor\/thumbs\/rafraichisseur-dair-2-p4om43po047vwbw02w1ajqvxri9o0n2rckuny1ed9c.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.rafraichisseur-air.fr\/it\/#website\",\"url\":\"https:\/\/www.rafraichisseur-air.fr\/it\/\",\"name\":\"Foxair\",\"description\":\"Rafra\u00eechisseur d&#039;air par \u00e9vaporation\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.rafraichisseur-air.fr\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deodoranti a motore EC: scopri FoxAir 36 EC","description":"Scopri il nostro raffreddatore ad aria con motore EC. Con FoxAir 36 EC puoi raffreddare fino a 260 m\u00b2 e ridurre il consumo energetico grazie all'innovativo motore a commutazione elettronica. Pi\u00f9 potente, pi\u00f9 silenzioso, ha tutte le carte in regola!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/","og_locale":"it_IT","og_type":"article","og_title":"Deodoranti a motore EC: scopri FoxAir 36 EC","og_description":"Scopri il nostro raffreddatore ad aria con motore EC. Con FoxAir 36 EC puoi raffreddare fino a 260 m\u00b2 e ridurre il consumo energetico grazie all'innovativo motore a commutazione elettronica. Pi\u00f9 potente, pi\u00f9 silenzioso, ha tutte le carte in regola!","og_url":"https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/","og_site_name":"Foxair","article_publisher":"https:\/\/www.facebook.com\/foxair.france","article_modified_time":"2024-07-08T14:33:53+00:00","og_image":[{"url":"https:\/\/www.rafraichisseur-air.fr\/wp-content\/uploads\/elementor\/thumbs\/rafraichisseur-dair-2-p4om43po047vwbw02w1ajqvxri9o0n2rckuny1ed9c.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/","url":"https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/","name":"Deodoranti a motore EC: scopri FoxAir 36 EC","isPartOf":{"@id":"https:\/\/www.rafraichisseur-air.fr\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/#primaryimage"},"image":{"@id":"https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rafraichisseur-air.fr\/wp-content\/uploads\/elementor\/thumbs\/rafraichisseur-dair-2-p4om43po047vwbw02w1ajqvxri9o0n2rckuny1ed9c.jpg","datePublished":"2019-03-29T15:30:31+00:00","dateModified":"2024-07-08T14:33:53+00:00","description":"Scopri il nostro raffreddatore ad aria con motore EC. Con FoxAir 36 EC puoi raffreddare fino a 260 m\u00b2 e ridurre il consumo energetico grazie all'innovativo motore a commutazione elettronica. Pi\u00f9 potente, pi\u00f9 silenzioso, ha tutte le carte in regola!","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rafraichisseur-air.fr\/it\/deodoranti-per-ambienti-a-motore-ec-il-nostro-modello-foxair-36-ec\/#primaryimage","url":"https:\/\/www.rafraichisseur-air.fr\/wp-content\/uploads\/elementor\/thumbs\/rafraichisseur-dair-2-p4om43po047vwbw02w1ajqvxri9o0n2rckuny1ed9c.jpg","contentUrl":"https:\/\/www.rafraichisseur-air.fr\/wp-content\/uploads\/elementor\/thumbs\/rafraichisseur-dair-2-p4om43po047vwbw02w1ajqvxri9o0n2rckuny1ed9c.jpg"},{"@type":"WebSite","@id":"https:\/\/www.rafraichisseur-air.fr\/it\/#website","url":"https:\/\/www.rafraichisseur-air.fr\/it\/","name":"Foxair","description":"Rafra\u00eechisseur d&#039;air par \u00e9vaporation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rafraichisseur-air.fr\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.rafraichisseur-air.fr\/it\/wp-json\/wp\/v2\/pages\/32814"}],"collection":[{"href":"https:\/\/www.rafraichisseur-air.fr\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rafraichisseur-air.fr\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rafraichisseur-air.fr\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rafraichisseur-air.fr\/it\/wp-json\/wp\/v2\/comments?post=32814"}],"version-history":[{"count":0,"href":"https:\/\/www.rafraichisseur-air.fr\/it\/wp-json\/wp\/v2\/pages\/32814\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.rafraichisseur-air.fr\/it\/wp-json\/wp\/v2\/media?parent=32814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}